{"id":14036,"date":"2022-06-28T12:41:57","date_gmt":"2022-06-28T10:41:57","guid":{"rendered":"https:\/\/www.imball.it\/cerradora-ci-30\/"},"modified":"2024-02-27T11:30:42","modified_gmt":"2024-02-27T10:30:42","slug":"cerradora-ci-30","status":"publish","type":"page","link":"https:\/\/www.imball.it\/es\/cerradora-ci-30\/","title":{"rendered":"cerradora CI 30"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14036\" class=\"elementor elementor-14036 elementor-4808\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-684be8f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"684be8f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4088397\" data-id=\"4088397\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17fd1a39 elementor-widget elementor-widget-heading\" data-id=\"17fd1a39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cerradora de cajas con<b> 3 solapas<\/b> en la tapa<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74953ba9 elementor-widget elementor-widget-heading\" data-id=\"74953ba9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">M\u00e1quina cerradora\nCI 30<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4161d79 elementor-widget-divider--view-line_icon elementor-widget-divider--element-align-left elementor-view-default elementor-widget elementor-widget-divider\" data-id=\"4161d79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-408aa219 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"408aa219\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-77f56610\" data-id=\"77f56610\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-234f79e6 elementor-widget elementor-widget-text-editor\" data-id=\"234f79e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La cerradora CI 30 es una m\u00e1quina autom\u00e1tica compacta adecuada para <strong>cajas medianas\/grandes como expositores de mostrador<\/strong>.<\/p>\n<p>Se utiliza principalmente en mercados alimentarios para productos como <strong>helados<\/strong>, <strong>aperitivos <\/strong>y <strong>snacks <\/strong>con velocidades de hasta <strong>30 cajas por minuto<\/strong>.<\/p>\n<p>Como todas las m\u00e1quinas autom\u00e1ticas Imball, dispone de protecciones transparentes de altura completa para una supervisi\u00f3n constante, tal y como exigen las normas alimentarias m\u00e1s estrictas.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eba7899 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eba7899\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bb1292d\" data-id=\"bb1292d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55ac0295 elementor-vertical-align-middle elementor-position-left elementor-widget elementor-widget-image-box\" data-id=\"55ac0295\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"58\" height=\"64\" src=\"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/fino-a.png\" class=\"attachment-full size-full wp-image-3859\" alt=\"\" srcset=\"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/fino-a.png 58w, https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/fino-a-45x50.png 45w\" sizes=\"(max-width:767px) 58px, 58px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Hasta 30 cajas\/minuto<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10a1c091 elementor-vertical-align-middle elementor-position-left elementor-widget elementor-widget-image-box\" data-id=\"10a1c091\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"54\" height=\"46\" src=\"https:\/\/www.imball.it\/wp-content\/uploads\/2023\/03\/scatole-3lembi-coperchio.png\" class=\"attachment-full size-full wp-image-6493\" alt=\"scatole 3 lembi sul coperchio\" srcset=\"https:\/\/www.imball.it\/wp-content\/uploads\/2023\/03\/scatole-3lembi-coperchio.png 54w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/03\/scatole-3lembi-coperchio-50x43.png 50w\" sizes=\"(max-width:767px) 54px, 54px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Para cajas con 3 solapas en la tapa<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14c2aec elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"14c2aec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"58\" height=\"64\" src=\"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/24-ore-7-giorni.png\" class=\"attachment-full size-full wp-image-4192\" alt=\"\" srcset=\"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/24-ore-7-giorni.png 58w, https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/24-ore-7-giorni-45x50.png 45w\" sizes=\"(max-width:767px) 58px, 58px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Eficacia operativa 24\/7<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99900e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99900e6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bb917ea\" data-id=\"bb917ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0081e84 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"0081e84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.imball.it\/wp-content\/uploads\/2023\/03\/DING_CI30.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Dimensiones de la m\u00e1quina<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c134ecf\" data-id=\"c134ecf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b9f811 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4b9f811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.imball.it\/es\/solicitud-de-folleto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DESCARGAR HOJA DE DATOS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e44dca9\" data-id=\"4e44dca9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b881cd2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b881cd2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-efca528\" data-id=\"efca528\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e2304b elementor-widget elementor-widget-image\" data-id=\"0e2304b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"649\" src=\"https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_solo_macchina.jpg\" class=\"attachment-full size-full wp-image-5722\" alt=\"Chiuditrice CI30 Imball\" srcset=\"https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_solo_macchina.jpg 600w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_solo_macchina-277x300.jpg 277w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_solo_macchina-135x146.jpg 135w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_solo_macchina-46x50.jpg 46w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_solo_macchina-69x75.jpg 69w\" sizes=\"(max-width:767px) 480px, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dea8c27 elementor-widget elementor-widget-image\" data-id=\"dea8c27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"266\" src=\"https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_cartoni.jpg\" class=\"attachment-full size-full wp-image-5723\" alt=\"Chiuditrice CI30 formazione scatole\" srcset=\"https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_cartoni.jpg 600w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_cartoni-300x133.jpg 300w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_cartoni-260x115.jpg 260w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_cartoni-50x22.jpg 50w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/02\/chiuditrice_CI30_cartoni-150x67.jpg 150w\" sizes=\"(max-width:767px) 480px, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d0a26a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d0a26a1\" data-element_type=\"section\" data-e-type=\"section\" id=\"dimensioni\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-419500f\" data-id=\"419500f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7749e2c7 elementor-widget elementor-widget-heading\" data-id=\"7749e2c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dimensiones del cart\u00f3n y del troquelado en mm<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7571914e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7571914e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37fc79e4\" data-id=\"37fc79e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45fb492e elementor-widget elementor-widget-image\" data-id=\"45fb492e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"624\" src=\"https:\/\/www.imball.it\/wp-content\/uploads\/2023\/03\/CI31_quote.jpg\" class=\"attachment-large size-large wp-image-6163\" alt=\"\" srcset=\"https:\/\/www.imball.it\/wp-content\/uploads\/2023\/03\/CI31_quote.jpg 595w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/03\/CI31_quote-286x300.jpg 286w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/03\/CI31_quote-139x146.jpg 139w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/03\/CI31_quote-48x50.jpg 48w, https:\/\/www.imball.it\/wp-content\/uploads\/2023\/03\/CI31_quote-72x75.jpg 72w\" sizes=\"(max-width:767px) 480px, 595px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ed575ee\" data-id=\"2ed575ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bc03ba8 elementor-widget elementor-widget-text-editor\" data-id=\"5bc03ba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table>\n<thead>\n<tr>\n<th class=\"clear\"> <\/th>\n<th>M\u00edn<\/th>\n<th>M\u00e1x<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"text-align: center;\">a<\/th>\n<td style=\"text-align: center;\">150<\/td>\n<td style=\"text-align: center;\">400<\/td>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">b<\/th>\n<td style=\"text-align: center;\">100<\/td>\n<td style=\"text-align: center;\">280<\/td>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">c<\/th>\n<td style=\"text-align: center;\">60<\/td>\n<td style=\"text-align: center;\">180<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ec01aa9 elementor-widget elementor-widget-text-editor\" data-id=\"1ec01aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se eval\u00faan diferentes dimensiones bajo pedido<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-540254a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"540254a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c5ae410\" data-id=\"6c5ae410\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e4dca09 elementor-widget elementor-widget-heading\" data-id=\"1e4dca09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Especificaciones<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34053091 elementor-widget-divider--view-line_icon elementor-widget-divider--element-align-left elementor-view-default elementor-widget elementor-widget-divider\" data-id=\"34053091\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-136a3cc8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"136a3cc8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-668bdb0d\" data-id=\"668bdb0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45a6e7eb elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"45a6e7eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1161\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1161\" aria-expanded=\"false\">Caracter\u00edsticas de serie<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1162\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1162\" aria-expanded=\"false\">Opcional<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1161\" aria-expanded=\"false\">Caracter\u00edsticas de serie<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1161\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1161\" tabindex=\"0\" hidden=\"false\"><p>Construcci\u00f3n robusta para garantizar una larga vida \u00fatil y la ausencia de vibraciones durante el ciclo de mecanizado<\/p>\n<p>Ajustes manuales con volantes e indicadores de posici\u00f3n<\/p>\n<p>Piezas mec\u00e1nicas con tratamientos antioxidantes<\/p>\n<p>Protecciones transparentes, piezas m\u00f3viles con micro de seguridad<\/p>\n<p>Cuadros el\u00e9ctricos y neum\u00e1ticos grandes y de f\u00e1cil acceso para el mantenimiento<\/p>\n<p>PLC de \u00faltima generaci\u00f3n y pantalla t\u00e1ctil HMI para gestionar todas las funciones<\/p>\n<p>Posibilidad de salida por la derecha o por la izquierda<\/p>\n<p>Encoladora termofusible de las mejores marcas con 3 pistolas<\/p>\n<p>Manual interactivo<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1162\" aria-expanded=\"false\">Opcional<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1162\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1162\" tabindex=\"0\" hidden=\"hidden\"><p>Ajustes autom\u00e1ticos gestionados por receta PLC<\/p>\n<p>Construcci\u00f3n de acero inoxidable<\/p>\n<p>Personalizaci\u00f3n de componentes y software  <\/p>\n<p><span style=\"color: var( --e-global-color-text ); letter-spacing: 0px;\">Teleasistencia<\/span><\/p>\n<p>Color RAL personalizado<\/p>\n<p>Climatizador del panel de control<\/p>\n<p>Preparaci\u00f3n para la Industria 4.0<\/p>\n<p><span style=\"font-family: Lato, sans-serif; font-size: 15px; font-style: normal; font-variant-caps: normal; color: var( --e-global-color-text ); letter-spacing: 0px;\">Marcador l\u00e1ser o de chorro de tinta<\/span><span style=\"font-family: Lato, sans-serif; font-size: 15px; font-style: normal; font-variant-caps: normal;\"> <\/span><\/p>\n<p><span style=\"font-family: Lato, sans-serif; font-size: 15px; font-style: normal; font-variant-caps: normal;\">Control \u00f3ptico, peso y rechazo  <\/span><\/p>\n<p><span style=\"font-family: Lato, sans-serif; font-size: 15px; font-style: normal; font-variant-caps: normal;\">Elevador de productos conforme a los transportadores a\u00e9reos<\/span><\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53b53f6b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"53b53f6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.imball.it\/es\/contactos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00bfEn qu\u00e9 podemos ayudarle?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cerradora de cajas con 3 solapas en la tapa M\u00e1quina cerradora CI 30 La cerradora CI 30 es una m\u00e1quina autom\u00e1tica compacta adecuada para cajas medianas\/grandes<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-14036","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cerradora autom\u00e1tica de cajas CI 30 | Imball<\/title>\n<meta name=\"description\" content=\"La cerradora CI 30 es una m\u00e1quina autom\u00e1tica compacta adecuada para cajas medianas\/grandes como expositores de mostrador.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cerradora autom\u00e1tica de cajas CI 30 | Imball\" \/>\n<meta property=\"og:description\" content=\"La cerradora CI 30 es una m\u00e1quina autom\u00e1tica compacta adecuada para cajas medianas\/grandes como expositores de mostrador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es\" \/>\n<meta property=\"og:site_name\" content=\"Imball\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-27T10:30:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/fino-a.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.imball.it\\\/cerradora-ci-30\\\/?lang=es\",\"url\":\"https:\\\/\\\/www.imball.it\\\/cerradora-ci-30\\\/?lang=es\",\"name\":\"Cerradora autom\u00e1tica de cajas CI 30 | Imball\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.imball.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.imball.it\\\/cerradora-ci-30\\\/?lang=es#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imball.it\\\/cerradora-ci-30\\\/?lang=es#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.imball.it\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/fino-a.png\",\"datePublished\":\"2022-06-28T10:41:57+00:00\",\"dateModified\":\"2024-02-27T10:30:42+00:00\",\"description\":\"La cerradora CI 30 es una m\u00e1quina autom\u00e1tica compacta adecuada para cajas medianas\\\/grandes como expositores de mostrador.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.imball.it\\\/cerradora-ci-30\\\/?lang=es#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.imball.it\\\/cerradora-ci-30\\\/?lang=es\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.imball.it\\\/cerradora-ci-30\\\/?lang=es#primaryimage\",\"url\":\"https:\\\/\\\/www.imball.it\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/fino-a.png\",\"contentUrl\":\"https:\\\/\\\/www.imball.it\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/fino-a.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.imball.it\\\/cerradora-ci-30\\\/?lang=es#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.imball.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cerradora CI 30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.imball.it\\\/#website\",\"url\":\"https:\\\/\\\/www.imball.it\\\/\",\"name\":\"Imball\",\"description\":\"Macchine Automatiche e Linee per il Packaging\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.imball.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.imball.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.imball.it\\\/#organization\",\"name\":\"Imball\",\"url\":\"https:\\\/\\\/www.imball.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.imball.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.imball.it\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Logo-Imball-512x512-bianco.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.imball.it\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Logo-Imball-512x512-bianco.jpeg\",\"width\":512,\"height\":512,\"caption\":\"Imball\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imball.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cerradora autom\u00e1tica de cajas CI 30 | Imball","description":"La cerradora CI 30 es una m\u00e1quina autom\u00e1tica compacta adecuada para cajas medianas\/grandes como expositores de mostrador.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es","og_locale":"es_ES","og_type":"article","og_title":"Cerradora autom\u00e1tica de cajas CI 30 | Imball","og_description":"La cerradora CI 30 es una m\u00e1quina autom\u00e1tica compacta adecuada para cajas medianas\/grandes como expositores de mostrador.","og_url":"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es","og_site_name":"Imball","article_modified_time":"2024-02-27T10:30:42+00:00","og_image":[{"url":"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/fino-a.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es","url":"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es","name":"Cerradora autom\u00e1tica de cajas CI 30 | Imball","isPartOf":{"@id":"https:\/\/www.imball.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es#primaryimage"},"image":{"@id":"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es#primaryimage"},"thumbnailUrl":"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/fino-a.png","datePublished":"2022-06-28T10:41:57+00:00","dateModified":"2024-02-27T10:30:42+00:00","description":"La cerradora CI 30 es una m\u00e1quina autom\u00e1tica compacta adecuada para cajas medianas\/grandes como expositores de mostrador.","breadcrumb":{"@id":"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es#primaryimage","url":"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/fino-a.png","contentUrl":"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/01\/fino-a.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.imball.it\/cerradora-ci-30\/?lang=es#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.imball.it\/"},{"@type":"ListItem","position":2,"name":"cerradora CI 30"}]},{"@type":"WebSite","@id":"https:\/\/www.imball.it\/#website","url":"https:\/\/www.imball.it\/","name":"Imball","description":"Macchine Automatiche e Linee per il Packaging","publisher":{"@id":"https:\/\/www.imball.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.imball.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.imball.it\/#organization","name":"Imball","url":"https:\/\/www.imball.it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.imball.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/06\/Logo-Imball-512x512-bianco.jpeg","contentUrl":"https:\/\/www.imball.it\/wp-content\/uploads\/2022\/06\/Logo-Imball-512x512-bianco.jpeg","width":512,"height":512,"caption":"Imball"},"image":{"@id":"https:\/\/www.imball.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.imball.it\/es\/wp-json\/wp\/v2\/pages\/14036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imball.it\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.imball.it\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.imball.it\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imball.it\/es\/wp-json\/wp\/v2\/comments?post=14036"}],"version-history":[{"count":2,"href":"https:\/\/www.imball.it\/es\/wp-json\/wp\/v2\/pages\/14036\/revisions"}],"predecessor-version":[{"id":14553,"href":"https:\/\/www.imball.it\/es\/wp-json\/wp\/v2\/pages\/14036\/revisions\/14553"}],"wp:attachment":[{"href":"https:\/\/www.imball.it\/es\/wp-json\/wp\/v2\/media?parent=14036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}